{"id":7276,"date":"2018-03-19T08:50:49","date_gmt":"2018-03-19T07:50:49","guid":{"rendered":"http:\/\/www.sogaenergyteam.com\/?p=7276"},"modified":"2018-04-17T12:13:47","modified_gmt":"2018-04-17T10:13:47","slug":"generatori-pto-a-cardano-agrowatt-sicurezza-da-leader","status":"publish","type":"post","link":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/","title":{"rendered":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-8a3689a5463c1fb4254888330a234775\">\n.avia-section.av-av_section-8a3689a5463c1fb4254888330a234775 .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator-1030x687.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-av_section-8a3689a5463c1fb4254888330a234775 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_one_fifth  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-7276'><div class='entry-content-wrapper clearfix'><\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-7276'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-av_one_fifth-2a9015ff38129c418a3f2eafba3e9512 av_one_fifth  avia-builder-el-1  el_after_av_section  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8 av_three_fifth  avia-builder-el-2  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-22b7a9dcbe109dc8424dd77b1f4cf31f\">\n.avia-image-container.av-av_image-22b7a9dcbe109dc8424dd77b1f4cf31f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-22b7a9dcbe109dc8424dd77b1f4cf31f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-22b7a9dcbe109dc8424dd77b1f4cf31f av-styling- avia-align-center  avia-builder-el-3  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-9890 avia-img-lazy-loading-not-9890 avia_image ' src=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2015\/10\/logo_agrowatt.jpg\" alt='' title='logo_agrowatt'  height=\"170\" width=\"600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2015\/10\/logo_agrowatt.jpg 600w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2015\/10\/logo_agrowatt-300x85.jpg 300w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2015\/10\/logo_agrowatt-450x128.jpg 450w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_fifth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_fifth  avia-builder-el-4  el_after_av_three_fifth  el_before_av_one_full  flex_column_div av-zero-column-padding  '     ><\/div>\n<div  class='flex_column av-av_one_full-2a9015ff38129c418a3f2eafba3e9512 av_one_full  avia-builder-el-5  el_after_av_one_fifth  el_before_av_one_full  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9\">\n#top .av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9{\npadding-bottom:1px;\ncolor:#6786a1;\nfont-size:30px;\n}\nbody .av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .av-special-heading-tag{\nfont-size:30px;\n}\n.av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .special-heading-inner-border{\nborder-color:#6786a1;\n}\n.av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-bb0e6e3253b1a89452f8cc9e24f3fda9 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-6  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >CERTIFICAZIONE PZ.LSV PER LE VERSIONI<br \/>\nFIELD E HOUSE\/FIELD GERMANIA<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-741ab06d0690c1111415ef58b6e9dc92\">\n#top .hr.hr-invisible.av-av_hr-741ab06d0690c1111415ef58b6e9dc92{\nheight:40px;\n}\n<\/style>\n<div  class='hr av-av_hr-741ab06d0690c1111415ef58b6e9dc92 hr-invisible  avia-builder-el-7  el_after_av_heading  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<div class='flex_column_table av-av_one_full-7b5c0400168a5f21d8e94e805fb2bc60 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-7b5c0400168a5f21d8e94e805fb2bc60\">\n.flex_column.av-av_one_full-7b5c0400168a5f21d8e94e805fb2bc60{\nborder-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-7b5c0400168a5f21d8e94e805fb2bc60 av_one_full  avia-builder-el-8  el_after_av_one_full  el_before_av_section  avia-builder-el-last  first flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-0edf5a2298c27ba4966f335fb0c79f08\">\n.avia-image-container.av-av_image-0edf5a2298c27ba4966f335fb0c79f08 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-0edf5a2298c27ba4966f335fb0c79f08 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-0edf5a2298c27ba4966f335fb0c79f08 av-styling- av-img-linked avia-align-center  avia-builder-el-9  el_before_av_hr  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"http:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat.pdf\" class='avia_image '  target=\"_blank\"  rel=\"noopener noreferrer\" aria-label='zapfwellengenerator PZ.LSV Zertifikat'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-9971 avia-img-lazy-loading-not-9971 avia_image ' src=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-180x180.jpg\" alt='' title='zapfwellengenerator PZ.LSV Zertifikat'  height=\"180\" width=\"180\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-180x180.jpg 180w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-80x80.jpg 80w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-300x300.jpg 300w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-36x36.jpg 36w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-120x120.jpg 120w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1-450x450.jpg 450w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/zapfwellengenerator-PZ.LSV-Zertifikat-1.jpg 500w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-741ab06d0690c1111415ef58b6e9dc92\">\n#top .hr.hr-invisible.av-av_hr-741ab06d0690c1111415ef58b6e9dc92{\nheight:40px;\n}\n<\/style>\n<div  class='hr av-av_hr-741ab06d0690c1111415ef58b6e9dc92 hr-invisible  avia-builder-el-10  el_after_av_image  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-586e525e8b2f90af96d78819b81aa3fa\">\n#top .av_textblock_section.av-av_textblock-586e525e8b2f90af96d78819b81aa3fa .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-586e525e8b2f90af96d78819b81aa3fa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>AgroWatt, leader di mercato nei generatori a cardano, si conferma all\u2019avanguardia anche in fatto di sicurezza.<\/p>\n<p>In un mercato caratterizzato da standard particolarmente esigenti, quale quello tedesco, abbiamo ottenuto l\u2019importante <strong>certificazione PZ.LSV <\/strong>estesa a tutti i nostri modelli con <strong>esecuzione specifica per la Germania<\/strong>, includendo entrambe le <strong>versioni <em>FIELD<\/em> e <em>HOUSE-FIELD<\/em><\/strong>.<\/p>\n<p>Un traguardo autorevole che attesta a livello formale, ma soprattutto sostanziale, gli <strong>elevatissimi standard di sicurezza<\/strong>, oltre che di ergonomia e praticit\u00e0, dei nostri generatori.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-586e525e8b2f90af96d78819b81aa3fa\">\n#top .av_textblock_section.av-av_textblock-586e525e8b2f90af96d78819b81aa3fa .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-586e525e8b2f90af96d78819b81aa3fa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Una scelta che mette in primo piano gli utilizzatori <\/strong>del nostro prodotto offrendo non soltanto prestazioni elettriche e meccaniche al top di gamma, ma anche <strong>protezione totale<\/strong> durante il lavoro quotidiano e in ogni tipo di utilizzo, e che posiziona il brand AgroWatt come il leader di riferimento per i generatori a cardano su scala internazionale.<\/p>\n<p><strong>AgroWatt, sempre un passo avanti!<\/strong><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-741ab06d0690c1111415ef58b6e9dc92\">\n#top .hr.hr-invisible.av-av_hr-741ab06d0690c1111415ef58b6e9dc92{\nheight:40px;\n}\n<\/style>\n<div  class='hr av-av_hr-741ab06d0690c1111415ef58b6e9dc92 hr-invisible  avia-builder-el-13  el_after_av_textblock  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-58d426ac15d5e2708f0d02582d043874\">\n.avia-section.av-av_section-58d426ac15d5e2708f0d02582d043874{\nbackground-color:#e5e5e5;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-av_section-58d426ac15d5e2708f0d02582d043874 main_color avia-section-default avia-no-shadow  avia-builder-el-14  el_after_av_one_full  el_before_av_masonry_gallery  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-7276'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-av_one_fourth-f7b5576bc84d51764353d1d6a46ea695 sc-av_one_fourth av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-f7b5576bc84d51764353d1d6a46ea695\">\n.flex_column.av-av_one_fourth-f7b5576bc84d51764353d1d6a46ea695{\nborder-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-f7b5576bc84d51764353d1d6a46ea695 av_one_fourth  avia-builder-el-15  el_before_av_one_fourth  avia-builder-el-first  first no_margin flex_column_table_cell av-equal-height-column av-align-middle  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-c2402208adf9ee3cfbf7c5c0483007f5\">\n.flex_column.av-av_one_fourth-c2402208adf9ee3cfbf7c5c0483007f5{\nborder-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-c2402208adf9ee3cfbf7c5c0483007f5 av_one_fourth  avia-builder-el-16  el_after_av_one_fourth  el_before_av_one_half  no_margin flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-8dd0005cf4317dece350c61bcb7e6f7d\">\n.avia-image-container.av-av_image-8dd0005cf4317dece350c61bcb7e6f7d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-8dd0005cf4317dece350c61bcb7e6f7d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-8dd0005cf4317dece350c61bcb7e6f7d av-styling- av-img-linked avia_animated_image av-animated-when-visible-95 fade-in avia-align-center  avia-builder-el-17  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat.jpg\" data-srcset=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat.jpg 673w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-212x300.jpg 212w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-498x705.jpg 498w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-450x637.jpg 450w\" data-sizes=\"(max-width: 673px) 100vw, 673px\" class='avia_image '  target=\"_blank\"  rel=\"noopener noreferrer\" aria-label='LSV zertifikat'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-9984 avia-img-lazy-loading-not-9984 avia_image ' src=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat.jpg\" alt='' title='LSV zertifikat'  height=\"952\" width=\"673\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat.jpg 673w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-212x300.jpg 212w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-498x705.jpg 498w, https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/LSV-zertifikat-450x637.jpg 450w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/><\/a><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-790321aabcdcb7d715377b51277f32b3\">\n.flex_column.av-av_one_half-790321aabcdcb7d715377b51277f32b3{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-790321aabcdcb7d715377b51277f32b3 av_one_half  avia-builder-el-18  el_after_av_one_fourth  avia-builder-el-last  no_margin flex_column_table_cell av-equal-height-column av-align-middle  '     ><p><div  class='avia-button-wrap av-av_button-53b2633ce7e6e0fad8893e93198b3281-wrap avia-button-left  avia-builder-el-19  el_before_av_button  avia-builder-el-first '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-53b2633ce7e6e0fad8893e93198b3281\">\n#top #wrap_all .avia-button.av-av_button-53b2633ce7e6e0fad8893e93198b3281{\nbackground-color:#6786a1;\nborder-color:#6786a1;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-av_button-53b2633ce7e6e0fad8893e93198b3281 .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='http:\/\/www.agrowatt.de'  class='avia-button av-av_button-53b2633ce7e6e0fad8893e93198b3281 av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-left'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Visita www.agrowatt.de\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue826' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Visita www.agrowatt.de<\/span><\/a><\/div><br \/>\n<div  class='avia-button-wrap av-av_button-5d7de7c5e0459bb8517cdda97a88e1bc-wrap avia-button-left  avia-builder-el-20  el_after_av_button  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-5d7de7c5e0459bb8517cdda97a88e1bc\">\n#top #wrap_all .avia-button.av-av_button-5d7de7c5e0459bb8517cdda97a88e1bc{\nbackground-color:#6786a1;\nborder-color:#6786a1;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-av_button-5d7de7c5e0459bb8517cdda97a88e1bc .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='https:\/\/www.linkedin.com\/company\/agrowat-deutschland\/'  class='avia-button av-av_button-5d7de7c5e0459bb8517cdda97a88e1bc av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-left'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Linkedin Agrowatt Deutschland\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue8fd' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Linkedin Agrowatt Deutschland<\/span><\/a><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n\n<div id='av-masonry-1' class='av-masonry av-av_masonry_gallery-dc642a519e3af362f50aab958a231b5d noHover av-fixed-size av-no-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-2 av-caption-always av-caption-style- av-masonry-gallery ' data-post_id=\"7276\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><div id='av-masonry-1-item-9970' data-av-masonry-item='9970' class='av-masonry-entry isotope-item post-9970 attachment type-attachment status-inherit hentry  av-masonry-item-with-image'    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/02\/tractor-driven-generator-agrowatt-1-705x469.jpg);\"  title=\"tractor driven generator agrowatt\" ><\/div><\/div><\/figure><\/div><!--end av-masonry entry--><div id='av-masonry-1-item-9990' data-av-masonry-item='9990' class='av-masonry-entry isotope-item post-9990 attachment type-attachment status-inherit hentry  av-masonry-item-with-image'    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/04\/zapfwellengenerator-705x631.jpg);\"  title=\"zapfwellengenerator\" ><\/div><\/div><\/figure><\/div><!--end av-masonry entry--><\/div><\/div>\n<div  class='hr av-av_hr-0ff602b3e980a3377077ff3c1c834df6 hr-default  avia-builder-el-22  el_after_av_masonry_gallery  avia-builder-el-no-sibling '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AgroWatt si conferma leader di mercato anche in fatto di sicurezza con l&#8217;ottenimento della certificazione PZ.LSV, estesa a tutti i nostri modelli con esecuzione specifica per la Germania. <\/p>\n","protected":false},"author":2,"featured_media":7851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140],"tags":[],"class_list":["post-7276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com<\/title>\n<meta name=\"description\" content=\"AgroWatt, leader nei generatori a cardano, si conferma all&#039;avanguardia anche in fatto di sicurezza con l&#039;ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com\" \/>\n<meta property=\"og:description\" content=\"AgroWatt, leader nei generatori a cardano, si conferma all&#039;avanguardia anche in fatto di sicurezza con l&#039;ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"www.sogaenergyteam.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-19T07:50:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-17T10:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sogaenergyteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sogaenergyteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\"},\"author\":{\"name\":\"sogaenergyteam\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297\"},\"headline\":\"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER\",\"datePublished\":\"2018-03-19T07:50:49+00:00\",\"dateModified\":\"2018-04-17T10:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\"},\"wordCount\":1036,\"image\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg\",\"articleSection\":[\"news @it\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\",\"url\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\",\"name\":\"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg\",\"datePublished\":\"2018-03-19T07:50:49+00:00\",\"dateModified\":\"2018-04-17T10:13:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297\"},\"description\":\"AgroWatt, leader nei generatori a cardano, si conferma all'avanguardia anche in fatto di sicurezza con l'ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage\",\"url\":\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg\",\"contentUrl\":\"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sogaenergyteam.com\/it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#website\",\"url\":\"https:\/\/www.sogaenergyteam.com\/it\/\",\"name\":\"www.sogaenergyteam.com\",\"description\":\"motori elettrici alternatori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sogaenergyteam.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297\",\"name\":\"sogaenergyteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b408d5d104dbe1a7f4e8f0ce66c84132202779905eb49d5b99be9bd5b6a1f85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b408d5d104dbe1a7f4e8f0ce66c84132202779905eb49d5b99be9bd5b6a1f85?s=96&d=mm&r=g\",\"caption\":\"sogaenergyteam\"},\"url\":\"https:\/\/www.sogaenergyteam.com\/it\/author\/soga\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com","description":"AgroWatt, leader nei generatori a cardano, si conferma all'avanguardia anche in fatto di sicurezza con l'ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/","og_locale":"it_IT","og_type":"article","og_title":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com","og_description":"AgroWatt, leader nei generatori a cardano, si conferma all'avanguardia anche in fatto di sicurezza con l'ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.","og_url":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/","og_site_name":"www.sogaenergyteam.com","article_published_time":"2018-03-19T07:50:49+00:00","article_modified_time":"2018-04-17T10:13:47+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg","type":"image\/jpeg"}],"author":"sogaenergyteam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"sogaenergyteam","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#article","isPartOf":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/"},"author":{"name":"sogaenergyteam","@id":"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297"},"headline":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER","datePublished":"2018-03-19T07:50:49+00:00","dateModified":"2018-04-17T10:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/"},"wordCount":1036,"image":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg","articleSection":["news @it"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/","url":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/","name":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER - www.sogaenergyteam.com","isPartOf":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage"},"image":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg","datePublished":"2018-03-19T07:50:49+00:00","dateModified":"2018-04-17T10:13:47+00:00","author":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297"},"description":"AgroWatt, leader nei generatori a cardano, si conferma all'avanguardia anche in fatto di sicurezza con l'ottenimento della certificazione PZ.LSV, estesa a tutti i modelli con esecuzione specifica per la Germania.","breadcrumb":{"@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#primaryimage","url":"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg","contentUrl":"https:\/\/www.sogaenergyteam.com\/wp-content\/uploads\/2018\/03\/pto-tractor-driven-generators-zapfwellengenerator.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.sogaenergyteam.com\/it\/generatori-pto-a-cardano-agrowatt-sicurezza-da-leader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sogaenergyteam.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"GENERATORI A CARDANO AGROWATT, SICUREZZA DA LEADER"}]},{"@type":"WebSite","@id":"https:\/\/www.sogaenergyteam.com\/it\/#website","url":"https:\/\/www.sogaenergyteam.com\/it\/","name":"www.sogaenergyteam.com","description":"motori elettrici alternatori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sogaenergyteam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/6194d2e0ecb3b8b7544c18aaa9fa7297","name":"sogaenergyteam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sogaenergyteam.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b408d5d104dbe1a7f4e8f0ce66c84132202779905eb49d5b99be9bd5b6a1f85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b408d5d104dbe1a7f4e8f0ce66c84132202779905eb49d5b99be9bd5b6a1f85?s=96&d=mm&r=g","caption":"sogaenergyteam"},"url":"https:\/\/www.sogaenergyteam.com\/it\/author\/soga\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/posts\/7276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/comments?post=7276"}],"version-history":[{"count":75,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/posts\/7276\/revisions"}],"predecessor-version":[{"id":7825,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/posts\/7276\/revisions\/7825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/media\/7851"}],"wp:attachment":[{"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/media?parent=7276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/categories?post=7276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sogaenergyteam.com\/it\/wp-json\/wp\/v2\/tags?post=7276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}